{"id":8669,"date":"2021-10-12T10:02:37","date_gmt":"2021-10-12T15:02:37","guid":{"rendered":"https:\/\/www.unaq.edu.mx\/?p=8669"},"modified":"2021-10-12T10:02:37","modified_gmt":"2021-10-12T15:02:37","slug":"firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa","status":"publish","type":"post","link":"https:\/\/www.unaq.edu.mx\/en\/noticias\/firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa\/","title":{"rendered":"Firma de convenio de colaboraci\u00f3n entre la UNAQ y la UPA"},"content":{"rendered":"<p>Quer\u00e9taro, Qro. 11 de octubre 2021<\/p>\n<p><span lang=\"ES\">Este lunes el Ing. Jorge Guti\u00e9rrez de Velasco, rector de la Universidad Aeron\u00e1utica en Quer\u00e9taro, y el Dr. Jes\u00fas Armando L\u00f3pez, rector de la Universidad Polit\u00e9cnica de Aguascalientes firmaron convenio de colaboraci\u00f3n con el objetivo de crear una efectiva vinculaci\u00f3n que facilite la realizaci\u00f3n de proyectos, programas y otras acciones en \u00e1reas acad\u00e9micas. \u00a0<\/span><\/p>\n<p class=\"x_MsoNormal\"><span lang=\"ES\">\u00a0<\/span><span lang=\"ES\">Dentro de este acuerdo de colaboraci\u00f3n ambas instituciones se comprometen a trabajar coordinadamente en la organizaci\u00f3n de cursos, jornadas acad\u00e9micas, conferencias, ponencias, desarrollo de actividades para servicio social o pr\u00e1cticas, entre otras. \u00a0<\/span><\/p>\n<p class=\"x_MsoNormal\"><span lang=\"ES\">\u00a0<\/span><span lang=\"ES\">La visita inici\u00f3 con un breve recorrido para que el personal de la UPA conociera las instalaciones de la UNAQ. Siguiendo con la firma de convenio, y concluyendo con la toma de fotograf\u00eda oficial. \u00a0<\/span><\/p>\n<p class=\"x_MsoNormal\"><span lang=\"ES\">\u00a0<\/span><span lang=\"ES\">Cabe mencionar que este acuerdo de colaboraci\u00f3n se deriv\u00f3 de un curso que la UNAQ brind\u00f3 al personal de la UPA donde se present\u00f3 la oportunidad de una donaci\u00f3n de cinco paneles did\u00e1cticos de arneses el\u00e9ctricos por parte de la UNAQ. \u00a0<\/span><\/p>\n<p class=\"x_MsoNormal\"><span lang=\"ES\">\u00a0<\/span><span lang=\"ES\">En el evento tambi\u00e9n se cont\u00f3 con la presencia de administrativos de la UPA:\u00a0\u00a0la M.C. Sandra Patricia Flores, secretaria acad\u00e9mica; el Mtro. Jorge Guerrero, director de vinculaci\u00f3n; la Dra. Susana V\u00e1zquez, directora de Ingenier\u00eda Aeron\u00e1utica; el Lic. Genaro Medrano, jefe de departamento de comunicaci\u00f3n; el Lic. Carlos Roberto, web master; y el TSU Hugo Alberto Peralta. Por parte de la UNAQ estuvieron presentes la M. en C. Norma Mu\u00f1oz, secretaria acad\u00e9mica; el Ing. Gerardo Cort\u00e9s, subdirector de vinculaci\u00f3n y desarrollo profesional; el Ing. Juan Antonio Robles, l\u00edder comercial; y el Lic. Agust\u00edn Alcocer, abogado general.\u00a0<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Quer\u00e9taro, Qro. 11 de octubre 2021 Este lunes el Ing. Jorge Guti\u00e9rrez de Velasco, rector de la Universidad Aeron\u00e1utica en Quer\u00e9taro, y el Dr. Jes\u00fas Armando L\u00f3pez, rector de la Universidad Polit\u00e9cnica de Aguascalientes firmaron convenio de colaboraci\u00f3n con el objetivo de crear una efectiva vinculaci\u00f3n que facilite la realizaci\u00f3n de proyectos, programas y otras [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8670,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-8669","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Firma de convenio de colaboraci\u00f3n entre la UNAQ y la UPA - UNAQ - Universidad Aeron&aacute;utica en Quer&eacute;taro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unaq.edu.mx\/en\/noticias\/firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Firma de convenio de colaboraci\u00f3n entre la UNAQ y la UPA - UNAQ - Universidad Aeron&aacute;utica en Quer&eacute;taro\" \/>\n<meta property=\"og:description\" content=\"Quer\u00e9taro, Qro. 11 de octubre 2021 Este lunes el Ing. Jorge Guti\u00e9rrez de Velasco, rector de la Universidad Aeron\u00e1utica en Quer\u00e9taro, y el Dr. Jes\u00fas Armando L\u00f3pez, rector de la Universidad Polit\u00e9cnica de Aguascalientes firmaron convenio de colaboraci\u00f3n con el objetivo de crear una efectiva vinculaci\u00f3n que facilite la realizaci\u00f3n de proyectos, programas y otras [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unaq.edu.mx\/en\/noticias\/firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa\/\" \/>\n<meta property=\"og:site_name\" content=\"UNAQ - Universidad Aeron&aacute;utica en Quer&eacute;taro\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UNAQMX\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-12T15:02:37+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@UNAQmx\" \/>\n<meta name=\"twitter:site\" content=\"@UNAQmx\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.unaq.edu.mx\\\/noticias\\\/firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unaq.edu.mx\\\/noticias\\\/firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.unaq.edu.mx\\\/#\\\/schema\\\/person\\\/24f098aa1760e7c165d176625485f080\"},\"headline\":\"Firma de convenio de colaboraci\u00f3n entre la UNAQ y la UPA\",\"datePublished\":\"2021-10-12T15:02:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.unaq.edu.mx\\\/noticias\\\/firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa\\\/\"},\"wordCount\":306,\"publisher\":{\"@id\":\"https:\\\/\\\/www.unaq.edu.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unaq.edu.mx\\\/noticias\\\/firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unaq.edu.mx\\\/noticias\\\/firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa\\\/\",\"url\":\"https:\\\/\\\/www.unaq.edu.mx\\\/noticias\\\/firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa\\\/\",\"name\":\"Firma de convenio de colaboraci\u00f3n entre la UNAQ y la UPA - UNAQ - Universidad Aeron&aacute;utica en Quer&eacute;taro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unaq.edu.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.unaq.edu.mx\\\/noticias\\\/firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unaq.edu.mx\\\/noticias\\\/firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2021-10-12T15:02:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unaq.edu.mx\\\/noticias\\\/firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unaq.edu.mx\\\/noticias\\\/firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.unaq.edu.mx\\\/noticias\\\/firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unaq.edu.mx\\\/noticias\\\/firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.unaq.edu.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Firma de convenio de colaboraci\u00f3n entre la UNAQ y la UPA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unaq.edu.mx\\\/#website\",\"url\":\"https:\\\/\\\/www.unaq.edu.mx\\\/\",\"name\":\"UNAQ - Universidad Aeron&aacute;utica en Quer&eacute;taro\",\"description\":\"Formamos profesionales e investigadores para el sector aeron&aacute;utico, con valores, conocimientos, competencias y reconocimiento nacional e internacional, basado en un modelo educativo abierto, flexible, pertinente y estrechamente vinculado, para el desarrollo social, econ&oacute;mico y cultural de M&eacute;xico.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.unaq.edu.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unaq.edu.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.unaq.edu.mx\\\/#organization\",\"name\":\"Universidad Aeron\u00e1utica en Quer\u00e9taro\",\"url\":\"https:\\\/\\\/www.unaq.edu.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.unaq.edu.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.unaq.edu.mx\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo_UNAQ.png\",\"contentUrl\":\"https:\\\/\\\/www.unaq.edu.mx\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo_UNAQ.png\",\"width\":648,\"height\":284,\"caption\":\"Universidad Aeron\u00e1utica en Quer\u00e9taro\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unaq.edu.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UNAQMX\\\/\",\"https:\\\/\\\/x.com\\\/UNAQmx\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/unaq\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/UNAQMX\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.unaq.edu.mx\\\/#\\\/schema\\\/person\\\/24f098aa1760e7c165d176625485f080\",\"name\":\"admin\",\"sameAs\":[\"https:\\\/\\\/www.unaq.edu.mx\"],\"url\":\"https:\\\/\\\/www.unaq.edu.mx\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Firma de convenio de colaboraci\u00f3n entre la UNAQ y la UPA - UNAQ - Universidad Aeron&aacute;utica en Quer&eacute;taro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unaq.edu.mx\/en\/noticias\/firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa\/","og_locale":"en_US","og_type":"article","og_title":"Firma de convenio de colaboraci\u00f3n entre la UNAQ y la UPA - UNAQ - Universidad Aeron&aacute;utica en Quer&eacute;taro","og_description":"Quer\u00e9taro, Qro. 11 de octubre 2021 Este lunes el Ing. Jorge Guti\u00e9rrez de Velasco, rector de la Universidad Aeron\u00e1utica en Quer\u00e9taro, y el Dr. Jes\u00fas Armando L\u00f3pez, rector de la Universidad Polit\u00e9cnica de Aguascalientes firmaron convenio de colaboraci\u00f3n con el objetivo de crear una efectiva vinculaci\u00f3n que facilite la realizaci\u00f3n de proyectos, programas y otras [&hellip;]","og_url":"https:\/\/www.unaq.edu.mx\/en\/noticias\/firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa\/","og_site_name":"UNAQ - Universidad Aeron&aacute;utica en Quer&eacute;taro","article_publisher":"https:\/\/www.facebook.com\/UNAQMX\/","article_published_time":"2021-10-12T15:02:37+00:00","author":"admin","twitter_card":"summary_large_image","twitter_creator":"@UNAQmx","twitter_site":"@UNAQmx","twitter_misc":{"Written by":"admin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.unaq.edu.mx\/noticias\/firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa\/#article","isPartOf":{"@id":"https:\/\/www.unaq.edu.mx\/noticias\/firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa\/"},"author":{"name":"admin","@id":"https:\/\/www.unaq.edu.mx\/#\/schema\/person\/24f098aa1760e7c165d176625485f080"},"headline":"Firma de convenio de colaboraci\u00f3n entre la UNAQ y la UPA","datePublished":"2021-10-12T15:02:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.unaq.edu.mx\/noticias\/firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa\/"},"wordCount":306,"publisher":{"@id":"https:\/\/www.unaq.edu.mx\/#organization"},"image":{"@id":"https:\/\/www.unaq.edu.mx\/noticias\/firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.unaq.edu.mx\/noticias\/firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa\/","url":"https:\/\/www.unaq.edu.mx\/noticias\/firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa\/","name":"Firma de convenio de colaboraci\u00f3n entre la UNAQ y la UPA - UNAQ - Universidad Aeron&aacute;utica en Quer&eacute;taro","isPartOf":{"@id":"https:\/\/www.unaq.edu.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.unaq.edu.mx\/noticias\/firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa\/#primaryimage"},"image":{"@id":"https:\/\/www.unaq.edu.mx\/noticias\/firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa\/#primaryimage"},"thumbnailUrl":"","datePublished":"2021-10-12T15:02:37+00:00","breadcrumb":{"@id":"https:\/\/www.unaq.edu.mx\/noticias\/firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unaq.edu.mx\/noticias\/firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.unaq.edu.mx\/noticias\/firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/www.unaq.edu.mx\/noticias\/firma-de-convenio-de-colaboracion-entre-la-unaq-y-la-upa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.unaq.edu.mx\/"},{"@type":"ListItem","position":2,"name":"Firma de convenio de colaboraci\u00f3n entre la UNAQ y la UPA"}]},{"@type":"WebSite","@id":"https:\/\/www.unaq.edu.mx\/#website","url":"https:\/\/www.unaq.edu.mx\/","name":"UNAQ - Universidad Aeron&aacute;utica en Quer&eacute;taro","description":"Formamos profesionales e investigadores para el sector aeron&aacute;utico, con valores, conocimientos, competencias y reconocimiento nacional e internacional, basado en un modelo educativo abierto, flexible, pertinente y estrechamente vinculado, para el desarrollo social, econ&oacute;mico y cultural de M&eacute;xico.","publisher":{"@id":"https:\/\/www.unaq.edu.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unaq.edu.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.unaq.edu.mx\/#organization","name":"Universidad Aeron\u00e1utica en Quer\u00e9taro","url":"https:\/\/www.unaq.edu.mx\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.unaq.edu.mx\/#\/schema\/logo\/image\/","url":"https:\/\/www.unaq.edu.mx\/wp-content\/uploads\/2022\/04\/Logo_UNAQ.png","contentUrl":"https:\/\/www.unaq.edu.mx\/wp-content\/uploads\/2022\/04\/Logo_UNAQ.png","width":648,"height":284,"caption":"Universidad Aeron\u00e1utica en Quer\u00e9taro"},"image":{"@id":"https:\/\/www.unaq.edu.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UNAQMX\/","https:\/\/x.com\/UNAQmx","https:\/\/www.linkedin.com\/company\/unaq","https:\/\/www.youtube.com\/user\/UNAQMX"]},{"@type":"Person","@id":"https:\/\/www.unaq.edu.mx\/#\/schema\/person\/24f098aa1760e7c165d176625485f080","name":"admin","sameAs":["https:\/\/www.unaq.edu.mx"],"url":"https:\/\/www.unaq.edu.mx\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.unaq.edu.mx\/en\/wp-json\/wp\/v2\/posts\/8669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unaq.edu.mx\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unaq.edu.mx\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unaq.edu.mx\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unaq.edu.mx\/en\/wp-json\/wp\/v2\/comments?post=8669"}],"version-history":[{"count":0,"href":"https:\/\/www.unaq.edu.mx\/en\/wp-json\/wp\/v2\/posts\/8669\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unaq.edu.mx\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.unaq.edu.mx\/en\/wp-json\/wp\/v2\/media?parent=8669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unaq.edu.mx\/en\/wp-json\/wp\/v2\/categories?post=8669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unaq.edu.mx\/en\/wp-json\/wp\/v2\/tags?post=8669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}